{"id":9155,"date":"2023-04-06T14:28:21","date_gmt":"2023-04-06T12:28:21","guid":{"rendered":"https:\/\/huehoco-gmbh.pixel-tal.de\/scaricamento\/certificati\/"},"modified":"2024-12-04T11:31:15","modified_gmt":"2024-12-04T10:31:15","slug":"certificati","status":"publish","type":"page","link":"https:\/\/huehoco.com\/it\/scaricamento\/certificati\/","title":{"rendered":"Certificati"},"content":{"rendered":"        \r\n            <!-- hero -->\r\n        \r\n                    \r\n            <div id=\"hero-14eee863e69862a550136e14e571603b\" class=\"hero\">\r\n\t\t\t\t<div class=\"hero-slider\">\t\t\t\t\n        \r\n            <!-- hero -->\r\n        \r\n                    \r\n            <div  class=\"hero-slide hero-slide-61b3da1ffb17194df24da2d72fb8a3e3 \">\r\n\r\n\t\t\t\t<div class=\"hero-canvas\">\r\n\t\t\t\t\t<div class=\"hero-content\">\r\n\t\t\t\t\t\t<span class=\"hero-subheadline subheadline\">Forniamo<\/span>\t\t\t\t\t\t<h1 class=\"hero-headline headline\">Qualit\u00e0 certificata<\/h1>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n                \t\t\t\t\t<div class=\"hero-background\">\r\n                        <div class=\"hero-overlay\"><\/div>\r\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/huehoco.com\/wp-content\/uploads\/hero-zertifikate.jpg\" \/>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\r\n                \r\n\t\t\t<\/div>\r\n        \r\n                    \r\n            <!-- end:hero -->\r\n        \r\n            \n\r\n\t\t\t\t<\/div>\t\t\t<\/div>\r\n        \r\n                    \r\n            <!-- end:hero -->\r\n        \r\n            \n\n<section class=\"gb-container gb-container-c0e9777e gb-container-section-white\">\n<div class=\"gb-container gb-container-d1592c45\">\n<div class=\"gb-grid-wrapper gb-grid-wrapper-277904a5\">\n<div class=\"gb-grid-column gb-grid-column-0afb2fa6\"><div class=\"gb-container gb-container-0afb2fa6\" data-aos=\"fade-right\">\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-top has-text-align-left\"><h2 class=\"headline\" style=\"color:\">I nostri certificati<\/h2><span class=\"subheadline\" style=\"color:\">Qualit\u00e0<\/span><\/div>\n\n\n\n<p>Il nostro Gruppo HUEHOCO si pone costantemente l&#8217;obiettivo di essere leader nei suoi mercati e pioniere nell&#8217;innovazione tecnica, nella qualit\u00e0 e nella tutela dell&#8217;ambiente.<\/p>\n\n\n\n<p>Per mantenere questo livello elevato, miglioriamo e sviluppiamo continuamente tutti i nostri prodotti. Si adattano in modo flessibile e rapido alle esigenze e alle applicazioni in costante evoluzione dei nostri clienti e del mercato.<\/p>\n\n\n\n<p>In questo modo, le certificazioni ci aiutano a mettere alla prova i nostri processi aziendali in modo permanente e ad allinearli con i parametri di riferimento di un metodo di best practice.<\/p>\n\n\n\n<p class=\"has-color-light-color has-text-color\"><strong>Solo cambiando diventiamo migliori.<\/strong><\/p>\n\n<\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-fef39065\"><div class=\"gb-container gb-container-fef39065\" data-aos=\"fade-left\">\n\n<figure class=\"gb-block-image gb-block-image-e23f938a\"><img loading=\"lazy\" decoding=\"async\" width=\"1810\" height=\"2560\" class=\"gb-image gb-image-e23f938a is-style-default\" src=\"https:\/\/huehoco.com\/wp-content\/uploads\/Zertifikat_Vorschau-scaled.jpg\" srcset=\"https:\/\/huehoco.com\/wp-content\/uploads\/Zertifikat_Vorschau-scaled.jpg 1810w, https:\/\/huehoco.com\/wp-content\/uploads\/Zertifikat_Vorschau-212x300.jpg 212w, https:\/\/huehoco.com\/wp-content\/uploads\/Zertifikat_Vorschau-724x1024.jpg 724w, https:\/\/huehoco.com\/wp-content\/uploads\/Zertifikat_Vorschau-768x1086.jpg 768w, https:\/\/huehoco.com\/wp-content\/uploads\/Zertifikat_Vorschau-1086x1536.jpg 1086w, https:\/\/huehoco.com\/wp-content\/uploads\/Zertifikat_Vorschau-1448x2048.jpg 1448w, https:\/\/huehoco.com\/wp-content\/uploads\/Zertifikat_Vorschau-53x75.jpg 53w, https:\/\/huehoco.com\/wp-content\/uploads\/Zertifikat_Vorschau-85x120.jpg 85w\" sizes=\"auto, (max-width: 1810px) 100vw, 1810px\" \/><\/figure>\n\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/section>\n\n<section class=\"gb-container gb-container-957773fe gb-container-section-metal\">\n<div class=\"gb-container gb-container-4357328c\">\n<div class=\"gb-grid-wrapper gb-grid-wrapper-582379fc\">\n<div class=\"gb-grid-column gb-grid-column-b0721bc9\"><div class=\"gb-container gb-container-b0721bc9\">\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-top has-text-align-left\"><h2 class=\"headline\" style=\"color:\">Certificazioni<\/h2><span class=\"subheadline\" style=\"color:\">Scaricamento<\/span><\/div>\n\n\n\n\t\t\t        \n                    \n            <div id=\"\" class=\"grid grid-2f8ec6af grid-download grid-columns-4\" >\n\t\t\t\t<div class=\"grid-inner\">\n\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"grid-item\">\n\t\t\t\t\t\t\t \r\n\t\t\t<div class=\"card card-download card-certificate\">\r\n\t\t\t\t<div class=\"card-media\"><div class='card-image'><a class=\"company-logo\" href=\"https:\/\/huehoco.com\/it\/standorte\/huehoco-gmbh\/\"><img loading=\"lazy\" decoding=\"async\" width=\"519\" height=\"120\" src=\"https:\/\/huehoco.com\/wp-content\/uploads\/huehoho-group-519x120.png\" class=\"attachment-company-logo-thumb size-company-logo-thumb wp-post-image\" alt=\"\" srcset=\"https:\/\/huehoco.com\/wp-content\/uploads\/huehoho-group-519x120.png 519w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoho-group-300x69.png 300w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoho-group-1024x237.png 1024w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoho-group-768x178.png 768w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoho-group-324x75.png 324w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoho-group.png 1232w\" sizes=\"auto, (max-width: 519px) 100vw, 519px\" \/><\/a><a class=\"card-featured\" target=\"_blank\" href=\"https:\/\/huehoco.com\/wp-content\/uploads\/HUEHOCO_GmbH_AEO_Zertifikat.pdf\"><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1500\" src=\"https:\/\/huehoco.com\/wp-content\/uploads\/huehoco_gmbh_aeo_zertifikat.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/huehoco.com\/wp-content\/uploads\/huehoco_gmbh_aeo_zertifikat.jpg 2000w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoco_gmbh_aeo_zertifikat-300x225.jpg 300w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoco_gmbh_aeo_zertifikat-1024x768.jpg 1024w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoco_gmbh_aeo_zertifikat-768x576.jpg 768w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoco_gmbh_aeo_zertifikat-1536x1152.jpg 1536w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoco_gmbh_aeo_zertifikat-100x75.jpg 100w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoco_gmbh_aeo_zertifikat-160x120.jpg 160w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/><\/a><\/div><\/div>\t\t\t\t<div class=\"card-content\">\r\n\t\t\t\t\t<div class=\"card-inner\">\r\n\t\t\t\t\t\t<a class=\"card-headline headline is-h4\" target=\"_blank\" href=\"https:\/\/huehoco.com\/wp-content\/uploads\/HUEHOCO_GmbH_AEO_Zertifikat.pdf\">Certificato AEO<\/a><span class=\"card-subheadline\">HUEHOCO GmbH<\/span>\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t<div class=\"card-action\"><a target=\"_blank\" class=\"card-link gb-button gb-button-arrowonly-light-blue\" href=\"https:\/\/huehoco.com\/wp-content\/uploads\/HUEHOCO_GmbH_AEO_Zertifikat.pdf\"><span class=\"gb-button-text\">Download<\/span><\/a><\/div>\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"grid-item\">\n\t\t\t\t\t\t\t \r\n\t\t\t<div class=\"card card-download card-certificate\">\r\n\t\t\t\t<div class=\"card-media\"><div class='card-image'><a class=\"company-logo\" href=\"https:\/\/huehoco.com\/it\/standorte\/huehoco-gmbh\/\"><img loading=\"lazy\" decoding=\"async\" width=\"519\" height=\"120\" src=\"https:\/\/huehoco.com\/wp-content\/uploads\/huehoho-group-519x120.png\" class=\"attachment-company-logo-thumb size-company-logo-thumb wp-post-image\" alt=\"\" srcset=\"https:\/\/huehoco.com\/wp-content\/uploads\/huehoho-group-519x120.png 519w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoho-group-300x69.png 300w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoho-group-1024x237.png 1024w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoho-group-768x178.png 768w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoho-group-324x75.png 324w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoho-group.png 1232w\" sizes=\"auto, (max-width: 519px) 100vw, 519px\" \/><\/a><a class=\"card-featured\" target=\"_blank\" href=\"https:\/\/huehoco.com\/wp-content\/uploads\/HUEHOCO-IATF-16949-EN-bis-27.10.2027.pdf\"><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1500\" src=\"https:\/\/huehoco.com\/wp-content\/uploads\/huehoco_gmbh_iatf_16949_2016.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" \/><\/a><\/div><\/div>\t\t\t\t<div class=\"card-content\">\r\n\t\t\t\t\t<div class=\"card-inner\">\r\n\t\t\t\t\t\t<a class=\"card-headline headline is-h4\" target=\"_blank\" href=\"https:\/\/huehoco.com\/wp-content\/uploads\/HUEHOCO-IATF-16949-EN-bis-27.10.2027.pdf\">IATF 16949<\/a><span class=\"card-subheadline\">HUEHOCO GmbH<\/span>\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t<div class=\"card-action\"><a target=\"_blank\" class=\"card-link gb-button gb-button-arrowonly-light-blue\" href=\"https:\/\/huehoco.com\/wp-content\/uploads\/HUEHOCO-IATF-16949-EN-bis-27.10.2027.pdf\"><span class=\"gb-button-text\">Download<\/span><\/a><\/div>\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"grid-item\">\n\t\t\t\t\t\t\t \r\n\t\t\t<div class=\"card card-download card-certificate\">\r\n\t\t\t\t<div class=\"card-media\"><div class='card-image'><a class=\"company-logo\" href=\"https:\/\/huehoco.com\/it\/standorte\/huehoco-gmbh\/\"><img loading=\"lazy\" decoding=\"async\" width=\"519\" height=\"120\" src=\"https:\/\/huehoco.com\/wp-content\/uploads\/huehoho-group-519x120.png\" class=\"attachment-company-logo-thumb size-company-logo-thumb wp-post-image\" alt=\"\" srcset=\"https:\/\/huehoco.com\/wp-content\/uploads\/huehoho-group-519x120.png 519w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoho-group-300x69.png 300w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoho-group-1024x237.png 1024w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoho-group-768x178.png 768w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoho-group-324x75.png 324w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoho-group.png 1232w\" sizes=\"auto, (max-width: 519px) 100vw, 519px\" \/><\/a><a class=\"card-featured\" target=\"_blank\" href=\"https:\/\/huehoco.com\/wp-content\/uploads\/huehoco_gmbh_50001_en.pdf\"><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1500\" src=\"https:\/\/huehoco.com\/wp-content\/uploads\/huehoco_gmbh_iso_50001_2023.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/huehoco.com\/wp-content\/uploads\/huehoco_gmbh_iso_50001_2023.jpg 2000w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoco_gmbh_iso_50001_2023-300x225.jpg 300w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoco_gmbh_iso_50001_2023-1024x768.jpg 1024w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoco_gmbh_iso_50001_2023-768x576.jpg 768w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoco_gmbh_iso_50001_2023-1536x1152.jpg 1536w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoco_gmbh_iso_50001_2023-100x75.jpg 100w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoco_gmbh_iso_50001_2023-160x120.jpg 160w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/><\/a><\/div><\/div>\t\t\t\t<div class=\"card-content\">\r\n\t\t\t\t\t<div class=\"card-inner\">\r\n\t\t\t\t\t\t<a class=\"card-headline headline is-h4\" target=\"_blank\" href=\"https:\/\/huehoco.com\/wp-content\/uploads\/huehoco_gmbh_50001_en.pdf\">DIN EN ISO 50001:2018<\/a><span class=\"card-subheadline\">HUEHOCO GmbH<\/span>\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t<div class=\"card-action\"><a target=\"_blank\" class=\"card-link gb-button gb-button-arrowonly-light-blue\" href=\"https:\/\/huehoco.com\/wp-content\/uploads\/huehoco_gmbh_50001_en.pdf\"><span class=\"gb-button-text\">Download<\/span><\/a><\/div>\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"grid-item\">\n\t\t\t\t\t\t\t \r\n\t\t\t<div class=\"card card-download card-certificate\">\r\n\t\t\t\t<div class=\"card-media\"><div class='card-image'><a class=\"company-logo\" href=\"https:\/\/huehoco.com\/it\/standorte\/huehoco-gmbh\/\"><img loading=\"lazy\" decoding=\"async\" width=\"519\" height=\"120\" src=\"https:\/\/huehoco.com\/wp-content\/uploads\/huehoho-group-519x120.png\" class=\"attachment-company-logo-thumb size-company-logo-thumb wp-post-image\" alt=\"\" srcset=\"https:\/\/huehoco.com\/wp-content\/uploads\/huehoho-group-519x120.png 519w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoho-group-300x69.png 300w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoho-group-1024x237.png 1024w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoho-group-768x178.png 768w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoho-group-324x75.png 324w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoho-group.png 1232w\" sizes=\"auto, (max-width: 519px) 100vw, 519px\" \/><\/a><a class=\"card-featured\" target=\"_blank\" href=\"https:\/\/huehoco.com\/wp-content\/uploads\/iso_14001_huehoco_en-1.pdf\"><img loading=\"lazy\" decoding=\"async\" width=\"2000\" height=\"1500\" src=\"https:\/\/huehoco.com\/wp-content\/uploads\/huehoco_gmbh_iso_14001_2023.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/huehoco.com\/wp-content\/uploads\/huehoco_gmbh_iso_14001_2023.jpg 2000w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoco_gmbh_iso_14001_2023-300x225.jpg 300w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoco_gmbh_iso_14001_2023-1024x768.jpg 1024w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoco_gmbh_iso_14001_2023-768x576.jpg 768w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoco_gmbh_iso_14001_2023-1536x1152.jpg 1536w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoco_gmbh_iso_14001_2023-100x75.jpg 100w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoco_gmbh_iso_14001_2023-160x120.jpg 160w\" sizes=\"auto, (max-width: 2000px) 100vw, 2000px\" \/><\/a><\/div><\/div>\t\t\t\t<div class=\"card-content\">\r\n\t\t\t\t\t<div class=\"card-inner\">\r\n\t\t\t\t\t\t<a class=\"card-headline headline is-h4\" target=\"_blank\" href=\"https:\/\/huehoco.com\/wp-content\/uploads\/iso_14001_huehoco_en-1.pdf\">DIN EN ISO 14001:2015<\/a><span class=\"card-subheadline\">HUEHOCO GmbH<\/span>\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t<div class=\"card-action\"><a target=\"_blank\" class=\"card-link gb-button gb-button-arrowonly-light-blue\" href=\"https:\/\/huehoco.com\/wp-content\/uploads\/iso_14001_huehoco_en-1.pdf\"><span class=\"gb-button-text\">Download<\/span><\/a><\/div>\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n            <\/div>\n\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\n            <!-- end:grid -->\n        \n            \n<\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-cc73c49a\"><div class=\"gb-container gb-container-cc73c49a\">\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-top has-text-align-left\"><h2 class=\"headline\" style=\"color:\">codice di condotta<\/h2><span class=\"subheadline\" style=\"color:\">Scaricamento<\/span><\/div>\n\n\n\n\t\t\t        \n                    \n            <div id=\"\" class=\"grid grid-2dd82908 grid-download grid-columns-4\" >\n\t\t\t\t<div class=\"grid-inner\">\n\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"grid-item\">\n\t\t\t\t\t\t\t \r\n\t\t\t<div class=\"card card-download\">\r\n\t\t\t\t<div class=\"card-media\"><a class=\"card-image\" target=\"_blank\" href=\"https:\/\/huehoco.com\/wp-content\/uploads\/Code-of-Conduct-HUEHOCO-GmbH-engl.pdf\"><img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"680\" src=\"https:\/\/huehoco.com\/wp-content\/uploads\/code_of_conduct.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/huehoco.com\/wp-content\/uploads\/code_of_conduct.jpg 780w, https:\/\/huehoco.com\/wp-content\/uploads\/code_of_conduct-300x262.jpg 300w, https:\/\/huehoco.com\/wp-content\/uploads\/code_of_conduct-768x670.jpg 768w, https:\/\/huehoco.com\/wp-content\/uploads\/code_of_conduct-86x75.jpg 86w, https:\/\/huehoco.com\/wp-content\/uploads\/code_of_conduct-138x120.jpg 138w\" sizes=\"auto, (max-width: 780px) 100vw, 780px\" \/><\/a><\/div>\t\t\t\t<div class=\"card-content\">\r\n\t\t\t\t\t<div class=\"card-inner\">\r\n\t\t\t\t\t\t<a class=\"card-headline headline is-h4\" target=\"_blank\" href=\"https:\/\/huehoco.com\/wp-content\/uploads\/Code-of-Conduct-HUEHOCO-GmbH-engl.pdf\">Code of Conduct HUEHOCO Group<\/a>\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t<div class=\"card-action\"><a target=\"_blank\" class=\"card-link gb-button gb-button-arrowonly-light-blue\" href=\"https:\/\/huehoco.com\/wp-content\/uploads\/Code-of-Conduct-HUEHOCO-GmbH-engl.pdf\"><span class=\"gb-button-text\">Download<\/span><\/a><\/div>\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"grid-item\">\n\t\t\t\t\t\t\t \r\n\t\t\t<div class=\"card card-download\">\r\n\t\t\t\t<div class=\"card-media\"><a class=\"card-image\" target=\"_blank\" href=\"https:\/\/huehoco.com\/wp-content\/uploads\/Environmental-and-energy-policy-of-the-HUEHOCO-Group.pdf\"><img loading=\"lazy\" decoding=\"async\" width=\"780\" height=\"680\" src=\"https:\/\/huehoco.com\/wp-content\/uploads\/code_of_conduct_1.jpg\" class=\"attachment-post-thumbnail size-post-thumbnail wp-post-image\" alt=\"\" srcset=\"https:\/\/huehoco.com\/wp-content\/uploads\/code_of_conduct_1.jpg 780w, https:\/\/huehoco.com\/wp-content\/uploads\/code_of_conduct_1-300x262.jpg 300w, https:\/\/huehoco.com\/wp-content\/uploads\/code_of_conduct_1-768x670.jpg 768w, https:\/\/huehoco.com\/wp-content\/uploads\/code_of_conduct_1-86x75.jpg 86w, https:\/\/huehoco.com\/wp-content\/uploads\/code_of_conduct_1-138x120.jpg 138w\" sizes=\"auto, (max-width: 780px) 100vw, 780px\" \/><\/a><\/div>\t\t\t\t<div class=\"card-content\">\r\n\t\t\t\t\t<div class=\"card-inner\">\r\n\t\t\t\t\t\t<a class=\"card-headline headline is-h4\" target=\"_blank\" href=\"https:\/\/huehoco.com\/wp-content\/uploads\/Environmental-and-energy-policy-of-the-HUEHOCO-Group.pdf\">Environmental and energy policy of the HUEHOCO Group<\/a>\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t<div class=\"card-action\"><a target=\"_blank\" class=\"card-link gb-button gb-button-arrowonly-light-blue\" href=\"https:\/\/huehoco.com\/wp-content\/uploads\/Environmental-and-energy-policy-of-the-HUEHOCO-Group.pdf\"><span class=\"gb-button-text\">Download<\/span><\/a><\/div>\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n            <\/div>\n\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\n            <!-- end:grid -->\n        \n            \n<\/div><\/div>\n<\/div>\n<\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":9093,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-9155","page","type-page","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Qualit\u00e0 certificata da HUEHOCO GmbH<\/title>\n<meta name=\"description\" content=\"Il nostro impegno per l&#039;eccellenza \u00e8 confermato dalle certificazioni del settore. Per saperne di pi\u00f9 sui nostri standard e scaricare i nostri certificati \u25b6 Leggi tutto\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/huehoco.com\/it\/scaricamento\/certificati\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Qualit\u00e0 certificata da HUEHOCO GmbH\" \/>\n<meta property=\"og:description\" content=\"Il nostro impegno per l&#039;eccellenza \u00e8 confermato dalle certificazioni del settore. Per saperne di pi\u00f9 sui nostri standard e scaricare i nostri certificati \u25b6 Leggi tutto\" \/>\n<meta property=\"og:url\" content=\"https:\/\/huehoco.com\/it\/scaricamento\/certificati\/\" \/>\n<meta property=\"og:site_name\" content=\"HUEHOCO GmbH\" \/>\n<meta property=\"article:modified_time\" content=\"2024-12-04T10:31:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/huehoco.com\/wp-content\/uploads\/Zertifikat_Vorschau-scaled.jpg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/huehoco.com\\\/it\\\/scaricamento\\\/certificati\\\/\",\"url\":\"https:\\\/\\\/huehoco.com\\\/it\\\/scaricamento\\\/certificati\\\/\",\"name\":\"Qualit\u00e0 certificata da HUEHOCO GmbH\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/huehoco.com\\\/it\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/huehoco.com\\\/it\\\/scaricamento\\\/certificati\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/huehoco.com\\\/it\\\/scaricamento\\\/certificati\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/huehoco.com\\\/wp-content\\\/uploads\\\/Zertifikat_Vorschau-scaled.jpg\",\"datePublished\":\"2023-04-06T12:28:21+00:00\",\"dateModified\":\"2024-12-04T10:31:15+00:00\",\"description\":\"Il nostro impegno per l'eccellenza \u00e8 confermato dalle certificazioni del settore. Per saperne di pi\u00f9 sui nostri standard e scaricare i nostri certificati \u25b6 Leggi tutto\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/huehoco.com\\\/it\\\/scaricamento\\\/certificati\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/huehoco.com\\\/it\\\/scaricamento\\\/certificati\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/huehoco.com\\\/it\\\/scaricamento\\\/certificati\\\/#primaryimage\",\"url\":\"https:\\\/\\\/huehoco.com\\\/wp-content\\\/uploads\\\/Zertifikat_Vorschau-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/huehoco.com\\\/wp-content\\\/uploads\\\/Zertifikat_Vorschau-scaled.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/huehoco.com\\\/it\\\/scaricamento\\\/certificati\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/huehoco.com\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Privat: Scaricamento\",\"item\":\"https:\\\/\\\/huehoco.com\\\/it\\\/?page_id=617\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Certificati\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/huehoco.com\\\/it\\\/#website\",\"url\":\"https:\\\/\\\/huehoco.com\\\/it\\\/\",\"name\":\"HUEHOCO GmbH\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/huehoco.com\\\/it\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/huehoco.com\\\/it\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/huehoco.com\\\/it\\\/#organization\",\"name\":\"HUEHOCO GmbH\",\"url\":\"https:\\\/\\\/huehoco.com\\\/it\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/huehoco.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/huehoco.com\\\/wp-content\\\/uploads\\\/huehoho-group.png\",\"contentUrl\":\"https:\\\/\\\/huehoco.com\\\/wp-content\\\/uploads\\\/huehoho-group.png\",\"width\":1232,\"height\":285,\"caption\":\"HUEHOCO GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/huehoco.com\\\/it\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Qualit\u00e0 certificata da HUEHOCO GmbH","description":"Il nostro impegno per l'eccellenza \u00e8 confermato dalle certificazioni del settore. Per saperne di pi\u00f9 sui nostri standard e scaricare i nostri certificati \u25b6 Leggi tutto","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/huehoco.com\/it\/scaricamento\/certificati\/","og_locale":"it_IT","og_type":"article","og_title":"Qualit\u00e0 certificata da HUEHOCO GmbH","og_description":"Il nostro impegno per l'eccellenza \u00e8 confermato dalle certificazioni del settore. Per saperne di pi\u00f9 sui nostri standard e scaricare i nostri certificati \u25b6 Leggi tutto","og_url":"https:\/\/huehoco.com\/it\/scaricamento\/certificati\/","og_site_name":"HUEHOCO GmbH","article_modified_time":"2024-12-04T10:31:15+00:00","og_image":[{"url":"https:\/\/huehoco.com\/wp-content\/uploads\/Zertifikat_Vorschau-scaled.jpg","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/huehoco.com\/it\/scaricamento\/certificati\/","url":"https:\/\/huehoco.com\/it\/scaricamento\/certificati\/","name":"Qualit\u00e0 certificata da HUEHOCO GmbH","isPartOf":{"@id":"https:\/\/huehoco.com\/it\/#website"},"primaryImageOfPage":{"@id":"https:\/\/huehoco.com\/it\/scaricamento\/certificati\/#primaryimage"},"image":{"@id":"https:\/\/huehoco.com\/it\/scaricamento\/certificati\/#primaryimage"},"thumbnailUrl":"https:\/\/huehoco.com\/wp-content\/uploads\/Zertifikat_Vorschau-scaled.jpg","datePublished":"2023-04-06T12:28:21+00:00","dateModified":"2024-12-04T10:31:15+00:00","description":"Il nostro impegno per l'eccellenza \u00e8 confermato dalle certificazioni del settore. Per saperne di pi\u00f9 sui nostri standard e scaricare i nostri certificati \u25b6 Leggi tutto","breadcrumb":{"@id":"https:\/\/huehoco.com\/it\/scaricamento\/certificati\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/huehoco.com\/it\/scaricamento\/certificati\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/huehoco.com\/it\/scaricamento\/certificati\/#primaryimage","url":"https:\/\/huehoco.com\/wp-content\/uploads\/Zertifikat_Vorschau-scaled.jpg","contentUrl":"https:\/\/huehoco.com\/wp-content\/uploads\/Zertifikat_Vorschau-scaled.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/huehoco.com\/it\/scaricamento\/certificati\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/huehoco.com\/it\/"},{"@type":"ListItem","position":2,"name":"Privat: Scaricamento","item":"https:\/\/huehoco.com\/it\/?page_id=617"},{"@type":"ListItem","position":3,"name":"Certificati"}]},{"@type":"WebSite","@id":"https:\/\/huehoco.com\/it\/#website","url":"https:\/\/huehoco.com\/it\/","name":"HUEHOCO GmbH","description":"","publisher":{"@id":"https:\/\/huehoco.com\/it\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/huehoco.com\/it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/huehoco.com\/it\/#organization","name":"HUEHOCO GmbH","url":"https:\/\/huehoco.com\/it\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/huehoco.com\/it\/#\/schema\/logo\/image\/","url":"https:\/\/huehoco.com\/wp-content\/uploads\/huehoho-group.png","contentUrl":"https:\/\/huehoco.com\/wp-content\/uploads\/huehoho-group.png","width":1232,"height":285,"caption":"HUEHOCO GmbH"},"image":{"@id":"https:\/\/huehoco.com\/it\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/huehoco.com\/it\/wp-json\/wp\/v2\/pages\/9155","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/huehoco.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/huehoco.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/huehoco.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/huehoco.com\/it\/wp-json\/wp\/v2\/comments?post=9155"}],"version-history":[{"count":1,"href":"https:\/\/huehoco.com\/it\/wp-json\/wp\/v2\/pages\/9155\/revisions"}],"predecessor-version":[{"id":10701,"href":"https:\/\/huehoco.com\/it\/wp-json\/wp\/v2\/pages\/9155\/revisions\/10701"}],"up":[{"embeddable":true,"href":"https:\/\/huehoco.com\/it\/wp-json\/wp\/v2\/pages\/9093"}],"wp:attachment":[{"href":"https:\/\/huehoco.com\/it\/wp-json\/wp\/v2\/media?parent=9155"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}