{"id":9125,"date":"2023-04-06T14:34:02","date_gmt":"2023-04-06T12:34:02","guid":{"rendered":"https:\/\/huehoco-gmbh.pixel-tal.de\/pongase-en-contacto-con\/"},"modified":"2023-10-16T12:08:30","modified_gmt":"2023-10-16T10:08:30","slug":"contacto","status":"publish","type":"page","link":"https:\/\/huehoco.com\/es\/contacto\/","title":{"rendered":"Contacto"},"content":{"rendered":"        \r\n            <!-- hero -->\r\n        \r\n                    \r\n            <div id=\"hero-8c9a3947a89e189f0adab9226f6093a4\" class=\"hero\">\r\n\t\t\t\t<div class=\"hero-slider\">\t\t\t\t\n        \r\n            <!-- hero -->\r\n        \r\n                    \r\n            <div  class=\"hero-slide hero-slide-8bf0008ac1c94db402737b8312c9a202 \">\r\n\r\n\t\t\t\t<div class=\"hero-canvas\">\r\n\t\t\t\t\t<div class=\"hero-content\">\r\n\t\t\t\t\t\t<span class=\"hero-subheadline subheadline\">Estamos a su disposici\u00f3n<\/span>\t\t\t\t\t\t<h1 class=\"hero-headline headline\">P\u00f3ngase en contacto con<\/h1>\t\t\t\t\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t<\/div>\r\n\r\n                \t\t\t\t\t<div class=\"hero-background\">\r\n                        <div class=\"hero-overlay\"><\/div>\r\n\t\t\t\t\t\t<img decoding=\"async\" src=\"https:\/\/huehoco.com\/wp-content\/uploads\/hero-ueberuns.jpg\" \/>\r\n\t\t\t\t\t<\/div>\r\n\t\t\t\t\r\n                \r\n\t\t\t<\/div>\r\n        \r\n                    \r\n            <!-- end:hero -->\r\n        \r\n            \n\r\n\t\t\t\t<\/div>\t\t\t<\/div>\r\n        \r\n                    \r\n            <!-- end:hero -->\r\n        \r\n            \n\n<section class=\"gb-container gb-container-47c2b55a gb-container-section-white\">\n<div class=\"gb-container gb-container-d91d2c69\">\n<div class=\"gb-grid-wrapper gb-grid-wrapper-683a6bb9\">\n<div class=\"gb-grid-column gb-grid-column-ee9940e4\"><div class=\"gb-container gb-container-ee9940e4\" data-aos=\"fade-right\">\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-top has-text-align-left\"><h2 class=\"headline\" style=\"color:\">Su persona de contacto<\/h2><span class=\"subheadline\" style=\"color:\">\u00bfObjetivos, planes, preguntas, deseos?<\/span><\/div>\n\n\n\n<p>No importa lo que podamos hacer por usted: estaremos encantados de escucharle. S\u00f3lo tiene que ponerse en contacto con nosotros, describirnos su preocupaci\u00f3n y puede estar seguro de que uno de nuestros expertos se pondr\u00e1 en contacto con usted como persona de contacto competente, y en el plazo m\u00e1s breve posible.  <\/p>\n\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/section>\n\n<section class=\"gb-container gb-container-1d80e449 gb-container-section-white\">\n<div class=\"gb-container gb-container-7b53083a\">\n<div class=\"gb-grid-wrapper gb-grid-wrapper-9723db10\">\n<div class=\"gb-grid-column gb-grid-column-4c1c550b\"><div class=\"gb-container gb-container-4c1c550b\" data-aos=\"fade-up\">\n\n\t\t\t        \n                    \n            <div id=\"\" class=\"grid grid-ab9e1fbf grid-contact grid-columns-4\" >\n\t\t\t\t<div class=\"grid-inner\">\n\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"grid-item\">\n\t\t\t\t\t\t\t \r\n\t\t\t<div class=\"card card-contact card-contact-small card-contact-8288\">\r\n\t\t\t\t<div class=\"card-media\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"485\" src=\"https:\/\/huehoco.com\/wp-content\/uploads\/jerkelenz.jpg\" class=\"attachment-contacts size-contacts\" alt=\"\" srcset=\"https:\/\/huehoco.com\/wp-content\/uploads\/jerkelenz.jpg 700w, https:\/\/huehoco.com\/wp-content\/uploads\/jerkelenz-300x208.jpg 300w, https:\/\/huehoco.com\/wp-content\/uploads\/jerkelenz-108x75.jpg 108w, https:\/\/huehoco.com\/wp-content\/uploads\/jerkelenz-173x120.jpg 173w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/div>\t\t\t\t<div class=\"card-content\">\r\n\t\t\t\t\t<div class=\"card-inner\">\r\n\t\t\t\t\t\t<h2 class=\"card-headline headline\">Joachim Erkelenz<\/h2><span class=\"card-subheadline\">Venta<\/span>\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t<div class=\"card-action\"><span class=\"card-line card-line-email\"><a href=\"mailto:j.erkelenz@huehoco.de\">Escribir mail<\/a><\/span><\/div>\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"grid-item\">\n\t\t\t\t\t\t\t \r\n\t\t\t<div class=\"card card-contact card-contact-small card-contact-8268\">\r\n\t\t\t\t<div class=\"card-media\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"485\" src=\"https:\/\/huehoco.com\/wp-content\/uploads\/mhofmann.jpg\" class=\"attachment-contacts size-contacts\" alt=\"\" srcset=\"https:\/\/huehoco.com\/wp-content\/uploads\/mhofmann.jpg 700w, https:\/\/huehoco.com\/wp-content\/uploads\/mhofmann-300x208.jpg 300w, https:\/\/huehoco.com\/wp-content\/uploads\/mhofmann-108x75.jpg 108w, https:\/\/huehoco.com\/wp-content\/uploads\/mhofmann-173x120.jpg 173w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/div>\t\t\t\t<div class=\"card-content\">\r\n\t\t\t\t\t<div class=\"card-inner\">\r\n\t\t\t\t\t\t<h2 class=\"card-headline headline\">Markus Hofmann<\/h2><span class=\"card-subheadline\">Head of Quality Assurance<\/span>\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t<div class=\"card-action\"><span class=\"card-line card-line-email\"><a href=\"mailto:m.hofmann@huehoco.de\">Escribir mail<\/a><\/span><\/div>\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"grid-item\">\n\t\t\t\t\t\t\t \r\n\t\t\t<div class=\"card card-contact card-contact-small card-contact-8277\">\r\n\t\t\t\t<div class=\"card-media\"><img loading=\"lazy\" decoding=\"async\" width=\"700\" height=\"485\" src=\"https:\/\/huehoco.com\/wp-content\/uploads\/huehoco-content-team-woker.jpg\" class=\"attachment-contacts size-contacts\" alt=\"\" srcset=\"https:\/\/huehoco.com\/wp-content\/uploads\/huehoco-content-team-woker.jpg 700w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoco-content-team-woker-300x208.jpg 300w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoco-content-team-woker-108x75.jpg 108w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoco-content-team-woker-173x120.jpg 173w\" sizes=\"auto, (max-width: 700px) 100vw, 700px\" \/><\/div>\t\t\t\t<div class=\"card-content\">\r\n\t\t\t\t\t<div class=\"card-inner\">\r\n\t\t\t\t\t\t<h2 class=\"card-headline headline\">Sabine Woker<\/h2><span class=\"card-subheadline\">Personal<\/span>\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t<div class=\"card-action\"><span class=\"card-line card-line-email\"><a href=\"mailto:bewerbung@huehoco.de\">Escribir mail<\/a><\/span><\/div>\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n            <\/div>\n\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\n            <!-- end:grid -->\n        \n            \n<\/div><\/div>\n<\/div>\n<\/div>\n<\/section>\n\n<section class=\"gb-container gb-container-04d57702 gb-container-section-metal\" id=\"contact\">\n<div class=\"gb-container gb-container-31e27eda\">\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-top has-text-align-left is-gap-sm\"><h2 class=\"headline\" style=\"color:\">P\u00f3ngase en contacto con nosotros<\/h2><span class=\"subheadline\" style=\"color:\">\u00bfObjetivos, planes, preguntas, deseos?<\/span><\/div>\n\n\n\t\t\t\t<div id=\"kontakt\" class=\"contact-form is-style-address gb-grid-wrapper\" >\r\n\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\t\t\t\t<address class=\"contact-form-side gb-grid-column\">\r\n\t\t\t\t\t\t \r\n\t\t\t<div class=\"card card-location card-location-8949\">\r\n\t\t\t\t<div class=\"card-media\"><img loading=\"lazy\" decoding=\"async\" width=\"1232\" height=\"285\" src=\"https:\/\/huehoco.com\/wp-content\/uploads\/huehoho-group.png\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/huehoco.com\/wp-content\/uploads\/huehoho-group.png 1232w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoho-group-300x69.png 300w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoho-group-1024x237.png 1024w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoho-group-768x178.png 768w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoho-group-324x75.png 324w, https:\/\/huehoco.com\/wp-content\/uploads\/huehoho-group-519x120.png 519w\" sizes=\"auto, (max-width: 1232px) 100vw, 1232px\" \/><\/div>\t\t\t\t<div class=\"card-content\">\r\n\t\t\t\t\t<div class=\"card-inner\">\r\n\t\t\t\t\t\t<span class=\"card-headline headline is-h4\">HUEHOCO Deutschland<\/span><div class=\"card-copy\"><span class=\"card-line card-line-street\">M\u00f6ddinghofe 31<\/span><span class=\"card-line card-line-city\">42279 Wuppertal<\/span><span class=\"card-line card-line-country\">Alemania<\/span><\/div>\t\t\t\t\t<\/div>\r\n\r\n\t\t\t\t\t<div class=\"card-action\"><span class=\"card-line card-line-fax\">+49 (0) 202 64778-69<\/span><span class=\"card-line card-line-email\"><a href=\"mailto:info@huehoco.de\">info@huehoco.de<\/a><\/span><span class=\"card-line card-line-maps\"><a class=\"gb-button gb-button-dark-blue-outlined is-style-outline\" href=\"https:\/\/www.google.com\/maps\/search\/?api=1&#038;query=HUEHOCO Deutschland+M\u00f6ddinghofe 31+42279 Wuppertal\" target=\"_blank\"><span class=\"gb-button-text\">Google Maps<\/span><\/span><\/a><\/span><\/div>\t\t\t\t<\/div>\r\n\t\t\t<\/div>\r\n\t\t\t\t\t\t\t\t<\/address>\t\r\n\t\t\t\t\t\r\n\t\t\t\t\t\t\t\r\n\t\t\t\t\t<div class=\"contact-form-main gb-grid-column\">\r\n                        \r\n                        \t\t\t\t\t\t\n<div class=\"wpcf7 no-js\" id=\"wpcf7-f8973-o1\" lang=\"es-ES\" dir=\"ltr\" data-wpcf7-id=\"8973\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/es\/wp-json\/wp\/v2\/pages\/9125#wpcf7-f8973-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Formulario de contacto\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"8973\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"es_ES\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f8973-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/>\n<\/fieldset>\n<div class=\"form-fields form-fields-3\">\n<div class=\"form-field\"><label>Nombre<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"fname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"fname\" \/><\/span><\/div>\n<div class=\"form-field\"><label>Nombre<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"lname\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"lname\" \/><\/span><\/div>\n<div class=\"form-field\"><label>Posici\u00f3n<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"position\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"position\" \/><\/span><\/div>\n<div class=\"form-field\"><label>Empresa<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"company\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"company\" \/><\/span><\/div>\n<div class=\"form-field\"><label>Tel\u00e9fono<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"phone\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text\" aria-invalid=\"false\" value=\"\" type=\"text\" name=\"phone\" \/><\/span><\/div>\n<div class=\"form-field\"><label>Correo electr\u00f3nico<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"mail\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" value=\"\" type=\"email\" name=\"mail\" \/><\/span><\/div>\n<\/div>\n<div class=\"form-field textarea\"><label>Su mensaje<\/label><span class=\"wpcf7-form-control-wrap\" data-name=\"message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" name=\"message\"><\/textarea><\/span><\/div>\n\n<span class=\"required\">Los campos marcados con * son obligatorios.<\/span>\n<div class=\"form-fields form-footer\">\n<div class=\"form-privacy\"><span class=\"wpcf7-form-control-wrap\" data-name=\"ds\"><span class=\"wpcf7-form-control wpcf7-acceptance\"><span class=\"wpcf7-list-item\"><input type=\"checkbox\" name=\"ds\" value=\"1\" aria-invalid=\"false\" \/><\/span><\/span><\/span><span class=\"privacy-policy-note\">Acepto la <a href=\"\/es\/legal\/proteccion-de-datos\/\" target=\"_blank\">pol\u00edtica de privacidad.<\/a><\/span><\/div>\n<span id=\"wpcf7-6a04a4195ac8f-wrapper\" class=\"wpcf7-form-control-wrap email-address-wrap\" style=\"display:none !important; visibility:hidden !important;\"><input type=\"hidden\" name=\"email-address-time-start\" value=\"1778689049\"><input type=\"hidden\" name=\"email-address-time-check\" value=\"2\"><label for=\"wpcf7-6a04a4195ac8f-field\" class=\"hp-message\">email-address<\/label><input id=\"wpcf7-6a04a4195ac8f-field\"  class=\"wpcf7-form-control wpcf7-text\" type=\"text\" name=\"email-address\" value=\"\" size=\"40\" tabindex=\"-1\" autocomplete=\"off\" \/><\/span>\n<div class=\"form-submit\"><button id=\"submit\" class=\"wpcf7-form-control wpcf7-submit\">Enviar<\/button><\/div>\n<\/div><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\t\t\t\t\t<\/div> \r\n\t\t\r\n\t\t\t\t<\/div>\r\n\t\t\t\n<\/div>\n<\/section>\n\n<section class=\"gb-container gb-container-62beaa58 gb-container-section-white\">\n<div class=\"gb-container gb-container-0add95c5\">\n<div class=\"gb-grid-wrapper gb-grid-wrapper-58b5c1ba\">\n<div class=\"gb-grid-column gb-grid-column-dd34ef90\"><div class=\"gb-container gb-container-dd34ef90\">\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-top has-text-align-left\"><h2 class=\"headline\" style=\"color:\">Direcciones de contacto<\/h2><span class=\"subheadline\" style=\"color:\">nuestras sedes internacionales y<\/span><\/div>\n\n\n\n <div class=\"brlbs-cmpnt-container brlbs-cmpnt-content-blocker brlbs-cmpnt-with-individual-styles\" data-borlabs-cookie-content-blocker-id=\"default\" data-borlabs-cookie-content=\"PGlmcmFtZSB3aWR0aD0iMTAwJSIgaGVpZ2h0PSI2MDBweCIgZnJhbWVib3JkZXI9IjAiIGFsbG93ZnVsbHNjcmVlbj0iIiBzcmM9Ii8vdW1hcC5vcGVuc3RyZWV0bWFwLmRlL2RlL21hcC9odWVob2NvLWdtYmhfNDMxNTE\/c2NhbGVDb250cm9sPWZhbHNlJm1pbmlNYXA9ZmFsc2Umc2Nyb2xsV2hlZWxab29tPWZhbHNlJnpvb21Db250cm9sPXRydWUmYWxsb3dFZGl0PWZhbHNlJm1vcmVDb250cm9sPXRydWUmc2VhcmNoQ29udHJvbD1udWxsJnRpbGVsYXllcnNDb250cm9sPW51bGwmZW1iZWRDb250cm9sPW51bGwmZGF0YWxheWVyc0NvbnRyb2w9dHJ1ZSZvbkxvYWRQYW5lbD11bmRlZmluZWQmY2FwdGlvbkJhcj1mYWxzZSI+PC9pZnJhbWU+\"><div class=\"brlbs-cmpnt-cb-preset-a\"> <p class=\"brlbs-cmpnt-cb-description\">Est\u00e1s viendo un contenido de marcador de posici\u00f3n de <strong>Predeterminado<\/strong>. Para acceder al contenido real, haz clic en el siguiente bot\u00f3n. Ten en cuenta que al hacerlo compartir\u00e1s datos con terceros proveedores.<\/p> <div class=\"brlbs-cmpnt-cb-buttons\"> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-unblock role=\"button\">Desbloquear contenido<\/a> <a class=\"brlbs-cmpnt-cb-btn\" href=\"#\" data-borlabs-cookie-accept-service role=\"button\" style=\"display: none\">Aceptar el servicio requerido y desbloquear los contenidos<\/a> <\/div> <a class=\"brlbs-cmpnt-cb-provider-toggle\" href=\"#\" data-borlabs-cookie-show-provider-information role=\"button\">M\u00e1s informaci\u00f3n<\/a> <\/div><\/div>\n\n<\/div><\/div>\n<\/div>\n<\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":9,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-9125","page","type-page","status-publish"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>P\u00f3ngase en contacto con nosotros<\/title>\n<meta name=\"description\" content=\"Estamos a su disposici\u00f3n. Si tiene preguntas o peticiones, p\u00f3ngase en contacto con nosotros y nuestro equipo de expertos se pondr\u00e1 en contacto con usted lo antes posible.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/huehoco.com\/es\/contacto\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"P\u00f3ngase en contacto con nosotros\" \/>\n<meta property=\"og:description\" content=\"Estamos a su disposici\u00f3n. Si tiene preguntas o peticiones, p\u00f3ngase en contacto con nosotros y nuestro equipo de expertos se pondr\u00e1 en contacto con usted lo antes posible.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/huehoco.com\/es\/contacto\/\" \/>\n<meta property=\"og:site_name\" content=\"HUEHOCO GmbH\" \/>\n<meta property=\"article:modified_time\" content=\"2023-10-16T10:08:30+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/huehoco.com\\\/es\\\/contacto\\\/\",\"url\":\"https:\\\/\\\/huehoco.com\\\/es\\\/contacto\\\/\",\"name\":\"P\u00f3ngase en contacto con nosotros\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/huehoco.com\\\/es\\\/#website\"},\"datePublished\":\"2023-04-06T12:34:02+00:00\",\"dateModified\":\"2023-10-16T10:08:30+00:00\",\"description\":\"Estamos a su disposici\u00f3n. Si tiene preguntas o peticiones, p\u00f3ngase en contacto con nosotros y nuestro equipo de expertos se pondr\u00e1 en contacto con usted lo antes posible.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/huehoco.com\\\/es\\\/contacto\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/huehoco.com\\\/es\\\/contacto\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/huehoco.com\\\/es\\\/contacto\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Startseite\",\"item\":\"https:\\\/\\\/huehoco.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Contacto\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/huehoco.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/huehoco.com\\\/es\\\/\",\"name\":\"HUEHOCO GmbH\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/huehoco.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/huehoco.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/huehoco.com\\\/es\\\/#organization\",\"name\":\"HUEHOCO GmbH\",\"url\":\"https:\\\/\\\/huehoco.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/huehoco.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/huehoco.com\\\/wp-content\\\/uploads\\\/huehoho-group.png\",\"contentUrl\":\"https:\\\/\\\/huehoco.com\\\/wp-content\\\/uploads\\\/huehoho-group.png\",\"width\":1232,\"height\":285,\"caption\":\"HUEHOCO GmbH\"},\"image\":{\"@id\":\"https:\\\/\\\/huehoco.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"P\u00f3ngase en contacto con nosotros","description":"Estamos a su disposici\u00f3n. Si tiene preguntas o peticiones, p\u00f3ngase en contacto con nosotros y nuestro equipo de expertos se pondr\u00e1 en contacto con usted lo antes posible.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/huehoco.com\/es\/contacto\/","og_locale":"es_ES","og_type":"article","og_title":"P\u00f3ngase en contacto con nosotros","og_description":"Estamos a su disposici\u00f3n. Si tiene preguntas o peticiones, p\u00f3ngase en contacto con nosotros y nuestro equipo de expertos se pondr\u00e1 en contacto con usted lo antes posible.","og_url":"https:\/\/huehoco.com\/es\/contacto\/","og_site_name":"HUEHOCO GmbH","article_modified_time":"2023-10-16T10:08:30+00:00","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/huehoco.com\/es\/contacto\/","url":"https:\/\/huehoco.com\/es\/contacto\/","name":"P\u00f3ngase en contacto con nosotros","isPartOf":{"@id":"https:\/\/huehoco.com\/es\/#website"},"datePublished":"2023-04-06T12:34:02+00:00","dateModified":"2023-10-16T10:08:30+00:00","description":"Estamos a su disposici\u00f3n. Si tiene preguntas o peticiones, p\u00f3ngase en contacto con nosotros y nuestro equipo de expertos se pondr\u00e1 en contacto con usted lo antes posible.","breadcrumb":{"@id":"https:\/\/huehoco.com\/es\/contacto\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/huehoco.com\/es\/contacto\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/huehoco.com\/es\/contacto\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Startseite","item":"https:\/\/huehoco.com\/es\/"},{"@type":"ListItem","position":2,"name":"Contacto"}]},{"@type":"WebSite","@id":"https:\/\/huehoco.com\/es\/#website","url":"https:\/\/huehoco.com\/es\/","name":"HUEHOCO GmbH","description":"","publisher":{"@id":"https:\/\/huehoco.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/huehoco.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/huehoco.com\/es\/#organization","name":"HUEHOCO GmbH","url":"https:\/\/huehoco.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/huehoco.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/huehoco.com\/wp-content\/uploads\/huehoho-group.png","contentUrl":"https:\/\/huehoco.com\/wp-content\/uploads\/huehoho-group.png","width":1232,"height":285,"caption":"HUEHOCO GmbH"},"image":{"@id":"https:\/\/huehoco.com\/es\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/huehoco.com\/es\/wp-json\/wp\/v2\/pages\/9125","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/huehoco.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/huehoco.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/huehoco.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/huehoco.com\/es\/wp-json\/wp\/v2\/comments?post=9125"}],"version-history":[{"count":0,"href":"https:\/\/huehoco.com\/es\/wp-json\/wp\/v2\/pages\/9125\/revisions"}],"wp:attachment":[{"href":"https:\/\/huehoco.com\/es\/wp-json\/wp\/v2\/media?parent=9125"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}